{"id":4833,"date":"2023-01-05T20:50:48","date_gmt":"2023-01-05T19:50:48","guid":{"rendered":"https:\/\/jagdklub-darmstadt.de\/hp\/?p=4833"},"modified":"2023-11-21T20:57:51","modified_gmt":"2023-11-21T19:57:51","slug":"jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd","status":"publish","type":"post","link":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/","title":{"rendered":"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen  &#8211;                                         Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)"},"content":{"rendered":"<p><strong>Die J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen &#8211;<\/strong><\/p>\n<p><strong>Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V. (JKD)<\/strong><\/p>\n<p>Stefan Bechtel (Mitglied des Vorstands JKD und Leiter der JKD Jagd- und Naturschutzschule Darmstadt) und Rainald Mohr (1. Vorsitzender des JKD) hatten es sich zur Aufgabe gemacht: In 2023 soll wieder die J\u00e4gerpr\u00fcfungskommission im Gro\u00dfraum Darmstadt einberufen werden. Konstruktive Gespr\u00e4che des JKD seitens des 1. Vorsitzenden Rainald Mohr mit der Oberen Jagdbeh\u00f6rde in Kassel waren der Auftakt. Stefan Bechtel vom JKD hat in einer Vielzahl von pers\u00f6nlichen Gespr\u00e4chen erfahrene Fachleute und J\u00e4ger aus der Region angesprochen, um diese f\u00fcr das anspruchsvolle und komplexe Ehrenamt eines Pr\u00fcfers zu gewinnen. So konnten Pr\u00fcfer gefunden werden, die im Jagdklub St. Hubertus Offenbach Stadt und Land e.V. (JKO), im Kreisj\u00e4gerverein Gro\u00df-Gerau e.V. (KJV Gro\u00df-Gerau) und im JKD beheimatet sind.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4846 aligncenter\" src=\"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/3-Pruefungskommission-300x132.jpg\" alt=\"\" width=\"787\" height=\"347\" srcset=\"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/3-Pruefungskommission-300x132.jpg 300w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/3-Pruefungskommission-600x265.jpg 600w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/3-Pruefungskommission-1024x452.jpg 1024w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/3-Pruefungskommission-768x339.jpg 768w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/3-Pruefungskommission-1536x678.jpg 1536w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/3-Pruefungskommission.jpg 1995w\" sizes=\"auto, (max-width: 787px) 100vw, 787px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Die k\u00fcnftige Pr\u00fcfungskommission hatte sich am 08.12.2022 im Jagdklub Darmstadt getroffen. Die Vorsitzende der Pr\u00fcfungskommission ist die J\u00e4gerin Frau Sylvia Henrici-Wick. Zu dem Treffen der Pr\u00fcfungskommission war die Obere Jagdbeh\u00f6rde aus Kassel ebenfalls eingeladen. Teilgenommen hat der zust\u00e4ndige Referent, Joachim Schramm des Dezernat Forsten &amp; Jagd vom Regierungspr\u00e4sidium Kassel. Die Zusammenkunft der Pr\u00fcfungskommission &#8211; an welcher auch Vorst\u00e4nde der drei beteiligten ortsans\u00e4ssigen Jagdvereine teilgenommen haben &#8211; diente dem gegenseitigen Kennenlernen und der Unterrichtung seitens Herrn Schramm \u00fcber Abl\u00e4ufe und Prozesse einer J\u00e4gerpr\u00fcfung. Eine Vielzahl von inhaltlichen Fragen in Bezug auf die Pr\u00fcfung wurden aufgeworfen und konnten durch Herrn Schramm beantwortet werden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4902 aligncenter\" src=\"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/4-Schramm-175x300.jpg\" alt=\"\" width=\"248\" height=\"425\" srcset=\"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/4-Schramm-175x300.jpg 175w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/4-Schramm.jpg 430w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/p>\n<p>Sp\u00e4testens zum Herbst 2023 wird die Pr\u00fcfungskommission erstmals einberufen. Ob die Pr\u00fcfungskommission bereits im Fr\u00fchjahr ihre erste J\u00e4gerpr\u00fcfung abh\u00e4lt wird derzeit noch seitens der Oberen Jagdbeh\u00f6rde gepr\u00fcft. Die Mitglieder der Pr\u00fcfungskommission haben einstimmig am 08.12.2022 ihrerseits die Bereitschaft hierzu bekundet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4977 aligncenter\" src=\"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/2-SylviaHenrici-Wick-251x300.jpg\" alt=\"\" width=\"251\" height=\"300\" srcset=\"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/2-SylviaHenrici-Wick-251x300.jpg 251w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/2-SylviaHenrici-Wick-856x1024.jpg 856w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/2-SylviaHenrici-Wick-768x919.jpg 768w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/2-SylviaHenrici-Wick-1284x1536.jpg 1284w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/2-SylviaHenrici-Wick-600x718.jpg 600w, https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2022\/12\/2-SylviaHenrici-Wick.jpg 1445w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/p>\n<p>Das Meeting fand in einer freundschaftlichen, lockeren und durch Hilfsbereitschaft gepr\u00e4gten Atmosph\u00e4re statt. Wichtige Netzwerke wurden gekn\u00fcpft. Der JKD, der JKO, und der KJV Gro\u00df-Gerau, die bei dem Thema \u201eGr\u00fcnes Abitur\u201c im Schulterschluss agieren, freuen sich, dass diese Zusammenkunft stattgefunden hat. Sie bedanken sich bei der neuen \u201ePr\u00fcfungskommission Darmstadt und Region\u201c sowie bei Herrn Joachim Schramm f\u00fcr die Teilnahme und f\u00fcr die k\u00fcnftige zu leistende Arbeit.<\/p>\n<p>R\u00fcckfragen gerne an den Autor: Rainald Mohr per E-mail\u00a0 <a href=\"mailto:1.Vorsitzender@jagdklub-darmstadt.de\">1.Vorsitzender@jagdklub-darmstadt.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen &#8211; Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V. (JKD) Stefan Bechtel (Mitglied des Vorstands JKD und Leiter [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":3293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[69,113],"tags":[185,187,184,120],"class_list":["post-4833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historie","category-jagdpolitik-rechtliches","tag-jagdklub_darmstadt","tag-jaeger_pruefungskommission","tag-jaegerpruefung","tag-rainald_mohr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD) - Jagdklub Darmstadt<\/title>\n<meta name=\"description\" content=\"Jagdklub Darmstadt - J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD) - Jagdklub Darmstadt\" \/>\n<meta property=\"og:description\" content=\"Jagdklub Darmstadt - J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/\" \/>\n<meta property=\"og:site_name\" content=\"Jagdklub Darmstadt\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-05T19:50:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-21T19:57:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2020\/04\/Jungjaeger2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ursel Bechtel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ursel Bechtel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/\"},\"author\":{\"name\":\"Ursel Bechtel\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#\\\/schema\\\/person\\\/14ebda9c1f9d7e152d89f42d0ebc2796\"},\"headline\":\"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen &#8211; Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)\",\"datePublished\":\"2023-01-05T19:50:48+00:00\",\"dateModified\":\"2023-11-21T19:57:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Jungjaeger2-scaled.jpg\",\"keywords\":[\"Jagdklub_Darmstadt\",\"J\u00e4ger_Pr\u00fcfungskommission\",\"J\u00e4gerpr\u00fcfung\",\"Rainald_Mohr\"],\"articleSection\":[\"Historie\",\"Jagdpolitik und Rechtliches\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/\",\"url\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/\",\"name\":\"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen - Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD) - Jagdklub Darmstadt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Jungjaeger2-scaled.jpg\",\"datePublished\":\"2023-01-05T19:50:48+00:00\",\"dateModified\":\"2023-11-21T19:57:51+00:00\",\"description\":\"Jagdklub Darmstadt - J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen - Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Jungjaeger2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Jungjaeger2-scaled.jpg\",\"width\":2560,\"height\":1787},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/2023\\\/01\\\/05\\\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen &#8211; Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#website\",\"url\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/\",\"name\":\"Jagdklub Darmstadt\",\"description\":\"Die Webseite des Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V.\",\"publisher\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#organization\",\"name\":\"Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V.\",\"url\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/JKD-Logo.png\",\"contentUrl\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/JKD-Logo.png\",\"width\":279,\"height\":361,\"caption\":\"Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/#\\\/schema\\\/person\\\/14ebda9c1f9d7e152d89f42d0ebc2796\",\"name\":\"Ursel Bechtel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ea123004a05cad2d0e262cd751e5f5b24f8e3c3447cec4ad151084b0e9391f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ea123004a05cad2d0e262cd751e5f5b24f8e3c3447cec4ad151084b0e9391f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ea123004a05cad2d0e262cd751e5f5b24f8e3c3447cec4ad151084b0e9391f?s=96&d=blank&r=g\",\"caption\":\"Ursel Bechtel\"},\"url\":\"https:\\\/\\\/jagdklub-darmstadt.de\\\/hp\\\/author\\\/u-bechtel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD) - Jagdklub Darmstadt","description":"Jagdklub Darmstadt - J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/","og_locale":"de_DE","og_type":"article","og_title":"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD) - Jagdklub Darmstadt","og_description":"Jagdklub Darmstadt - J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen -                     Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)","og_url":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/","og_site_name":"Jagdklub Darmstadt","article_published_time":"2023-01-05T19:50:48+00:00","article_modified_time":"2023-11-21T19:57:51+00:00","og_image":[{"width":2560,"height":1787,"url":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2020\/04\/Jungjaeger2-scaled.jpg","type":"image\/jpeg"}],"author":"Ursel Bechtel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ursel Bechtel","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#article","isPartOf":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/"},"author":{"name":"Ursel Bechtel","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#\/schema\/person\/14ebda9c1f9d7e152d89f42d0ebc2796"},"headline":"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen &#8211; Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)","datePublished":"2023-01-05T19:50:48+00:00","dateModified":"2023-11-21T19:57:51+00:00","mainEntityOfPage":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#organization"},"image":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#primaryimage"},"thumbnailUrl":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2020\/04\/Jungjaeger2-scaled.jpg","keywords":["Jagdklub_Darmstadt","J\u00e4ger_Pr\u00fcfungskommission","J\u00e4gerpr\u00fcfung","Rainald_Mohr"],"articleSection":["Historie","Jagdpolitik und Rechtliches"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/","url":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/","name":"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen - Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD) - Jagdklub Darmstadt","isPartOf":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#primaryimage"},"image":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#primaryimage"},"thumbnailUrl":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2020\/04\/Jungjaeger2-scaled.jpg","datePublished":"2023-01-05T19:50:48+00:00","dateModified":"2023-11-21T19:57:51+00:00","description":"Jagdklub Darmstadt - J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen - Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)","breadcrumb":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#primaryimage","url":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2020\/04\/Jungjaeger2-scaled.jpg","contentUrl":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2020\/04\/Jungjaeger2-scaled.jpg","width":2560,"height":1787},{"@type":"BreadcrumbList","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/2023\/01\/05\/jaeger-pruefungskommission-darmstadt-wird-wieder-einberufen-versammlung-der-kommission-im-vereinshaus-des-jagdklub-darmstadt-jkd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/jagdklub-darmstadt.de\/hp\/"},{"@type":"ListItem","position":2,"name":"J\u00e4ger-Pr\u00fcfungskommission Darmstadt wird wieder einberufen &#8211; Versammlung der Kommission im Vereinshaus des Jagdklub Darmstadt (JKD)"}]},{"@type":"WebSite","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#website","url":"https:\/\/jagdklub-darmstadt.de\/hp\/","name":"Jagdklub Darmstadt","description":"Die Webseite des Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V.","publisher":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jagdklub-darmstadt.de\/hp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#organization","name":"Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V.","url":"https:\/\/jagdklub-darmstadt.de\/hp\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#\/schema\/logo\/image\/","url":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2016\/06\/JKD-Logo.png","contentUrl":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-content\/uploads\/2016\/06\/JKD-Logo.png","width":279,"height":361,"caption":"Jagdklub Darmstadt, Verein f\u00fcr J\u00e4ger und Sportsch\u00fctzen e.V."},"image":{"@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jagdklub-darmstadt.de\/hp\/#\/schema\/person\/14ebda9c1f9d7e152d89f42d0ebc2796","name":"Ursel Bechtel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b5ea123004a05cad2d0e262cd751e5f5b24f8e3c3447cec4ad151084b0e9391f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5ea123004a05cad2d0e262cd751e5f5b24f8e3c3447cec4ad151084b0e9391f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5ea123004a05cad2d0e262cd751e5f5b24f8e3c3447cec4ad151084b0e9391f?s=96&d=blank&r=g","caption":"Ursel Bechtel"},"url":"https:\/\/jagdklub-darmstadt.de\/hp\/author\/u-bechtel\/"}]}},"_links":{"self":[{"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/posts\/4833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/comments?post=4833"}],"version-history":[{"count":30,"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/posts\/4833\/revisions"}],"predecessor-version":[{"id":4990,"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/posts\/4833\/revisions\/4990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/media\/3293"}],"wp:attachment":[{"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/media?parent=4833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/categories?post=4833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jagdklub-darmstadt.de\/hp\/wp-json\/wp\/v2\/tags?post=4833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}